{"id":1175,"date":"2022-06-23T13:09:27","date_gmt":"2022-06-23T19:09:27","guid":{"rendered":"https:\/\/encontacto.asefemsa.com\/?p=1175"},"modified":"2022-06-23T13:09:28","modified_gmt":"2022-06-23T19:09:28","slug":"nosotros-lavamos-su-vehiculo-mientras-usted-trabaja","status":"publish","type":"post","link":"https:\/\/encontacto.asefemsa.com\/index.php\/2022\/06\/23\/nosotros-lavamos-su-vehiculo-mientras-usted-trabaja\/","title":{"rendered":"Nosotros lavamos su veh\u00edculo, mientras usted trabaja"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le invitamos a coordinar con el Encargado del Parqueo de ASEMFESA, para lavar su veh\u00edculo mientras usted realiza su jornada laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El precio del servicio de Biolavado es: \u00a24.000<br>Lavado, aspirado interior y lavado de alfombras<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Formas de Pago:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Efectivo<\/li><li>Tarjeta<\/li><li>SINPE M\u00f3vil al 8735-3286<\/li><li>Financiamiento seg\u00fan disponible (Tasa 0% a un mes plazo)<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contacto para consultas:<\/strong>\u00a02247-2099 ext. 2581<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le invitamos a coordinar con el Encargado del Parqueo de ASEMFESA, para lavar su veh\u00edculo mientras usted realiza su jornada laboral.<\/p>\n<a href=\"https:\/\/encontacto.asefemsa.com\/index.php\/2022\/06\/23\/nosotros-lavamos-su-vehiculo-mientras-usted-trabaja\/\" class=\"more-link\">Leer m\u00e1s<\/a>","protected":false},"author":1,"featured_media":1176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beneficios","col-xs-12"],"_links":{"self":[{"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/posts\/1175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/comments?post=1175"}],"version-history":[{"count":1,"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/posts\/1175\/revisions"}],"predecessor-version":[{"id":1177,"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/posts\/1175\/revisions\/1177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/media\/1176"}],"wp:attachment":[{"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/media?parent=1175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/categories?post=1175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/encontacto.asefemsa.com\/index.php\/wp-json\/wp\/v2\/tags?post=1175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}